{"id":1991,"count":4,"description":"Die Kollektion M\u00e9moire Breuning vereint Eheringe aus Wei\u00dfgold 585, die auf einem Teil der Ringschiene mit Diamanten besetzt sind. Das Design bleibt schlicht und ausgewogen, mit einer klaren Linie, die die Regelm\u00e4\u00dfigkeit der Fassung und das Funkeln der Steine betont. Insgesamt entsteht ein zeitgem\u00e4\u00dfer, pr\u00e4ziser und eleganter Stil, gedacht f\u00fcr einen raffinierten Ehering im t\u00e4glichen Tragen.","link":"https:\/\/gil-bonnet.ch\/de\/marke\/breuning\/memoire\/","name":"Memoire","slug":"memoire","taxonomy":"product_brand","parent":1188,"meta":[],"_links":{"self":[{"href":"https:\/\/gil-bonnet.ch\/de\/wp-json\/wp\/v2\/product_brand\/1991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gil-bonnet.ch\/de\/wp-json\/wp\/v2\/product_brand"}],"about":[{"href":"https:\/\/gil-bonnet.ch\/de\/wp-json\/wp\/v2\/taxonomies\/product_brand"}],"up":[{"embeddable":true,"href":"https:\/\/gil-bonnet.ch\/de\/wp-json\/wp\/v2\/product_brand\/1188"}],"wp:post_type":[{"href":"https:\/\/gil-bonnet.ch\/de\/wp-json\/wp\/v2\/product?product_brand=1991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}